{"id":2227,"date":"2025-09-17T13:18:16","date_gmt":"2025-09-17T13:18:16","guid":{"rendered":"https:\/\/cero.com.pt\/?page_id=2227"},"modified":"2025-09-22T15:35:21","modified_gmt":"2025-09-22T15:35:21","slug":"pediatric-dentistry","status":"publish","type":"page","link":"https:\/\/cero.com.pt\/en\/pediatric-dentistry\/","title":{"rendered":"Pediatric Dentistry"},"content":{"rendered":"<section class=\"l-section wpb_row us_custom_a53ec023 height_small\"><div class=\"l-section-overlay\" style=\"background:var(--color-alt-content-overlay)\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-vwrapper align_center valign_top\" style=\"--vwrapper-gap:0rem\"><div class=\"wpb_text_column us_custom_8b3d6790 has_text_color\"><div class=\"wpb_wrapper\"><h6>Dentistry<\/h6>\n<\/div><\/div><div class=\"wpb_text_column us_custom_8b3d6790 has_text_color\"><div class=\"wpb_wrapper\"><h1>Pediatric Dentistry<\/h1>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_custom\"><div class=\"l-section-overlay\" style=\"background:var(--color-content-bg-alt)\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2-3 laptops-cols_inherit tablets-cols_1 mobiles-cols_1 valign_middle type_default reversed stacking_default\" style=\"--gap:5rem;--laptops-gap:5rem;--tablets-gap:3rem;--mobiles-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image imgcurva hide_on_tablets hide_on_mobiles has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:112.5%\"><\/div><img decoding=\"async\" width=\"662\" height=\"600\" src=\"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/06\/Odontopediatria-5.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><div class=\"w-image imgcurva hide_on_default hide_on_laptops has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:66.6667%\"><\/div><img decoding=\"async\" width=\"662\" height=\"600\" src=\"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/06\/Odontopediatria-5.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><div class=\"w-separator hide_on_default hide_on_laptops size_medium\"><\/div><div class=\"w-btn-wrapper align_center hide_on_default hide_on_laptops\"><a class=\"w-btn us-btn-style_1\" href=\"https:\/\/cero.com.pt\/en\/contacts\/#consulta\"><span class=\"w-btn-label\">Book Appointment<\/span><\/a><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"100\" height=\"64\" src=\"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/04\/logo-primario-1-100x64.png\" class=\"attachment-us_100_100 size-us_100_100\" alt=\"logo\" loading=\"lazy\" srcset=\"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/04\/logo-primario-1-100x64.png 100w, https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/04\/logo-primario-1-300x193.png 300w, https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/04\/logo-primario-1-150x97.png 150w, https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/04\/logo-primario-1.png 500w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:1.2rem\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>The world of Pediatric Dentistry at our clinic is of great importance. Our main goal is to transform the dental visit for our children into a safe and relaxed environment. We aim to show them that taking care of our teeth is easy and that going to the dentist should be part of everyone\u2019s routine.<\/p>\n<p>Starting care from the first year of life allows us to educate them and help parents take care of their children&#8217;s teeth from an early age.<\/p>\n<p>It also allows us to diagnose and correct early problems related to misalignment of the dental arches, early childhood cavities, and helps eliminate habits such as pacifiers and thumb sucking.<\/p>\n<\/div><\/div><\/div><div class=\"w-separator hide_on_tablets hide_on_mobiles size_small\"><\/div><div class=\"w-btn-wrapper align_none hide_on_tablets hide_on_mobiles\"><a class=\"w-btn us-btn-style_1\" href=\"https:\/\/cero.com.pt\/en\/contacts\/#consulta\"><span class=\"w-btn-label\">Book Appointment<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_custom\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_1 mobiles-cols_1 valign_middle type_default stacking_default\" style=\"--gap:5rem;--laptops-gap:5rem;--tablets-gap:3rem;--mobiles-gap:3rem;\"><div class=\"wpb_column vc_column_container gridnumeros\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_33aadde5 has_text_color\"><div class=\"wpb_wrapper\"><p><em><span style=\"font-weight: 400; color: #00687a;\">The main goal of CERO KIDS is personalized care, attentive to the needs of each of our little ones<\/span>, using various means to demystify all the procedures performed.<\/em><\/p>\n<p><em>By using a bit of imagination and some touches of magic, <span style=\"font-weight: 400; color: #00687a;\">we strive to create empathy and a relationship of trust with our patients, hoping that at the end of each visit, they are excited to return to our clinic.<\/span><\/em><\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-hwrapper valign_top align_right\"><div class=\"wpb_text_column us_custom_687cc40e\"><div class=\"wpb_wrapper\"><p>&#8211; Dr. Patr\u00edcia Martins, Pediatric Dentist<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_custom\"><div class=\"l-section-overlay\" style=\"background:var(--color-content-bg-alt)\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_1 mobiles-cols_1 valign_middle type_default stacking_default\" style=\"--gap:5rem;--laptops-gap:5rem;--tablets-gap:3rem;--mobiles-gap:3rem;\"><div class=\"wpb_column vc_column_container gridnumeros\"><div class=\"vc_column-inner\"><div class=\"g-cols wpb_row via_grid cols_2-3 laptops-cols_2-3 tablets-cols_1 mobiles-cols_1 valign_middle type_default stacking_default\" style=\"--gap:3rem;--laptops-gap:3rem;--tablets-gap:1rem;--mobiles-gap:1rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3>What <span class=\"h3color\">types of consultations<\/span> are available?<\/h3>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><\/div><\/div><\/div><div class=\"w-separator size_custom\" style=\"height:2em\"><\/div><div class=\"g-cols wpb_row via_grid cols_2 laptops-cols_inherit tablets-cols_1 mobiles-cols_1 valign_top type_default stacking_default\" style=\"--gap:3rem;--laptops-gap:3rem;--tablets-gap:0.1rem;--mobiles-gap:0.1rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-tabs style_default switch_click accordion\" style=\"--sections-title-size:inherit\"><div class=\"w-tabs-sections titles-align_none icon_plus cpos_right\"><div class=\"w-tabs-section\" id=\"a214\"><button class=\"w-tabs-section-header\" aria-controls=\"content-a214\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Pregnant Woman Consultation<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-a214\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Advice during pregnancy and on the first oral hygiene and breastfeeding care for the baby. Guidance on pacifiers, bottles, and other instruments used that impact the oral cavity.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"l3ac\"><button class=\"w-tabs-section-header\" aria-controls=\"content-l3ac\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">First Pediatric Dentistry Consultation<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-l3ac\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Recommended from the eruption of the first tooth or up to 1 year of age, according to WHO guidelines.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-tabs style_default switch_click accordion\" style=\"--sections-title-size:inherit\"><div class=\"w-tabs-sections titles-align_none icon_plus cpos_right\"><div class=\"w-tabs-section\" id=\"qd89\"><button class=\"w-tabs-section-header\" aria-controls=\"content-qd89\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Preventive Dental Medicine Consultations<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-qd89\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Recommended every 6 months for oral hygiene with topical fluoride application and X-rays to detect dental caries.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"of64\"><button class=\"w-tabs-section-header\" aria-controls=\"content-of64\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Other Treatments and Consultations<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-of64\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><ul>\n<li>Restorative treatments for cavities, trauma, or enamel defects.<\/li>\n<li>Endodontic treatments \u2013 pulpotomies and pulpectomies.<\/li>\n<li>Pediatric metal crowns for posterior spaces.<\/li>\n<li>Pediatric zirconia crowns for anterior spaces.<\/li>\n<li>Space maintainers for premature tooth loss.<\/li>\n<li>Interceptive orthodontics.<\/li>\n<li>Consultations with conscious sedation.<\/li>\n<li>Consultations with general anesthesia.<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_custom\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_3-2 laptops-cols_inherit tablets-cols_1 mobiles-cols_1 valign_middle type_default stacking_default\" style=\"--gap:5rem;--laptops-gap:5rem;--tablets-gap:3rem;--mobiles-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:1.2rem\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3>Conscious Sedation: <span class=\"h3color\">Questions and Reasons<\/span><\/h3>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>The use of Conscious Sedation in Pediatric Dentistry appointments is a behavior control mechanism designed to facilitate dental treatments for our child patients.<\/p>\n<p>It is a mild state of sedation in which the patient remains awake, alert, and able to respond to stimuli and verbal commands. N\u2082O, nitrous oxide, is a colorless gas with a slightly sweet smell and taste. It is neither flammable, irritating, nor toxic to the child or those around them.<\/p>\n<p>It requires the use of a nasal mask and demands nasal breathing from the patient, thus requiring cooperation. Full recovery of consciousness is achieved within approximately 10 to 15 minutes through the inhalation of pure oxygen.<\/p>\n<p>A preliminary induction and familiarization appointment is conducted, allowing the child to see and try the nasal mask to build confidence and trust with the CERO KIDS Team. This appointment is also essential for taking the patient&#8217;s medical and clinical history and determining whether they are suitable for the procedure.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image imgcurva hide_on_tablets hide_on_mobiles has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:128.5714%\"><\/div><img decoding=\"async\" width=\"662\" height=\"600\" src=\"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/05\/Sedacao-Consciente.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><div class=\"w-image imgcurva hide_on_default hide_on_laptops has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:66.6667%\"><\/div><img decoding=\"async\" width=\"662\" height=\"600\" src=\"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/05\/Sedacao-Consciente.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row hide_on_default hide_on_laptops hide_on_tablets hide_on_mobiles height_custom\"><div class=\"l-section-overlay\" style=\"background:var(--color-content-bg-alt)\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><section class=\"l-section wpb_row height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2-3 laptops-cols_inherit tablets-cols_1 mobiles-cols_1 valign_middle type_default reversed stacking_default\" style=\"--gap:5rem;--laptops-gap:5rem;--tablets-gap:3rem;--mobiles-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image imgcurva hide_on_tablets hide_on_mobiles has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:75%\"><\/div><img decoding=\"async\" width=\"1024\" height=\"654\" src=\"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/05\/Patricia-Lima.jpg\" class=\"attachment-large size-large\" alt=\"Patr\u00edcia Lima\" loading=\"lazy\" \/><\/div><\/div><div class=\"w-image imgcurva hide_on_default hide_on_laptops has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:66.6667%\"><\/div><img decoding=\"async\" width=\"1024\" height=\"654\" src=\"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/05\/Patricia-Lima.jpg\" class=\"attachment-large size-large\" alt=\"Patr\u00edcia Lima\" loading=\"lazy\" \/><\/div><\/div><div class=\"w-separator hide_on_default hide_on_laptops size_medium\"><\/div><div class=\"w-btn-wrapper align_center hide_on_default hide_on_laptops\"><a class=\"w-btn us-btn-style_3\" href=\"https:\/\/cero.com.pt\/en\/dr-tiago-ribeiro\/\"><span class=\"w-btn-label\">Learn more<\/span><\/a><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h6>Pediatric dentistry<\/h6>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:0.5em\"><\/div><div class=\"w-vwrapper align_none valign_top\" style=\"--vwrapper-gap:1.2rem\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3><span class=\"h3color\">Dr.<\/span>  Patr\u00edcia Lima<\/h3>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Lorem ipsum dolor sit amet, consectetur adipiscing elit. <\/p>\n<p>Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat.<\/p>\n<\/div><\/div><\/div><div class=\"w-separator hide_on_tablets hide_on_mobiles size_small\"><\/div><div class=\"w-btn-wrapper align_none hide_on_tablets hide_on_mobiles\"><a class=\"w-btn us-btn-style_3\" href=\"https:\/\/cero.com.pt\/en\/dr-tiago-ribeiro\/\"><span class=\"w-btn-label\">Learn more<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/section>\n<\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Dentistry Pediatric Dentistry Book AppointmentThe world of Pediatric Dentistry at our clinic is of great importance. Our main goal is to transform the dental visit for our children into a safe and relaxed environment. We aim to show them that taking care of our teeth is easy and that going to the dentist should be...","protected":false},"author":1,"featured_media":1694,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-2227","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Odontopediatria: Cuidados e Atendimento Infantil | CERO KIDS<\/title>\n<meta name=\"description\" content=\"Descubra como a Odontopediatria na CERO KIDS oferece cuidados personalizados para crian\u00e7as desde o primeiro ano de vida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cero.com.pt\/en\/pediatric-dentistry\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Odontopediatria: Cuidados e Atendimento Infantil | CERO KIDS\" \/>\n<meta property=\"og:description\" content=\"Descubra como a Odontopediatria na CERO KIDS oferece cuidados personalizados para crian\u00e7as desde o primeiro ano de vida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cero.com.pt\/en\/pediatric-dentistry\/\" \/>\n<meta property=\"og:site_name\" content=\"CERO\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-22T15:35:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/06\/Odontopediatria-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1130\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cero.com.pt\\\/en\\\/pediatric-dentistry\\\/\",\"url\":\"https:\\\/\\\/cero.com.pt\\\/en\\\/pediatric-dentistry\\\/\",\"name\":\"Odontopediatria: Cuidados e Atendimento Infantil | CERO KIDS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cero.com.pt\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cero.com.pt\\\/en\\\/pediatric-dentistry\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cero.com.pt\\\/en\\\/pediatric-dentistry\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cero.com.pt\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Odontopediatria-4.jpg\",\"datePublished\":\"2025-09-17T13:18:16+00:00\",\"dateModified\":\"2025-09-22T15:35:21+00:00\",\"description\":\"Descubra como a Odontopediatria na CERO KIDS oferece cuidados personalizados para crian\u00e7as desde o primeiro ano de vida.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cero.com.pt\\\/en\\\/pediatric-dentistry\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cero.com.pt\\\/en\\\/pediatric-dentistry\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cero.com.pt\\\/en\\\/pediatric-dentistry\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cero.com.pt\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Odontopediatria-4.jpg\",\"contentUrl\":\"https:\\\/\\\/cero.com.pt\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Odontopediatria-4.jpg\",\"width\":1130,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cero.com.pt\\\/en\\\/pediatric-dentistry\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cero.com.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pediatric Dentistry\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cero.com.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/cero.com.pt\\\/en\\\/\",\"name\":\"CERO\",\"description\":\"Sorrisos de Confian\u00e7a!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cero.com.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Odontopediatria: Cuidados e Atendimento Infantil | CERO KIDS","description":"Descubra como a Odontopediatria na CERO KIDS oferece cuidados personalizados para crian\u00e7as desde o primeiro ano de vida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cero.com.pt\/en\/pediatric-dentistry\/","og_locale":"en_US","og_type":"article","og_title":"Odontopediatria: Cuidados e Atendimento Infantil | CERO KIDS","og_description":"Descubra como a Odontopediatria na CERO KIDS oferece cuidados personalizados para crian\u00e7as desde o primeiro ano de vida.","og_url":"https:\/\/cero.com.pt\/en\/pediatric-dentistry\/","og_site_name":"CERO","article_modified_time":"2025-09-22T15:35:21+00:00","og_image":[{"width":1130,"height":1024,"url":"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/06\/Odontopediatria-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cero.com.pt\/en\/pediatric-dentistry\/","url":"https:\/\/cero.com.pt\/en\/pediatric-dentistry\/","name":"Odontopediatria: Cuidados e Atendimento Infantil | CERO KIDS","isPartOf":{"@id":"https:\/\/cero.com.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cero.com.pt\/en\/pediatric-dentistry\/#primaryimage"},"image":{"@id":"https:\/\/cero.com.pt\/en\/pediatric-dentistry\/#primaryimage"},"thumbnailUrl":"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/06\/Odontopediatria-4.jpg","datePublished":"2025-09-17T13:18:16+00:00","dateModified":"2025-09-22T15:35:21+00:00","description":"Descubra como a Odontopediatria na CERO KIDS oferece cuidados personalizados para crian\u00e7as desde o primeiro ano de vida.","breadcrumb":{"@id":"https:\/\/cero.com.pt\/en\/pediatric-dentistry\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cero.com.pt\/en\/pediatric-dentistry\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cero.com.pt\/en\/pediatric-dentistry\/#primaryimage","url":"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/06\/Odontopediatria-4.jpg","contentUrl":"https:\/\/cero.com.pt\/wp-content\/uploads\/2024\/06\/Odontopediatria-4.jpg","width":1130,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/cero.com.pt\/en\/pediatric-dentistry\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cero.com.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Pediatric Dentistry"}]},{"@type":"WebSite","@id":"https:\/\/cero.com.pt\/en\/#website","url":"https:\/\/cero.com.pt\/en\/","name":"CERO","description":"Sorrisos de Confian\u00e7a!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cero.com.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/cero.com.pt\/en\/wp-json\/wp\/v2\/pages\/2227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cero.com.pt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cero.com.pt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cero.com.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cero.com.pt\/en\/wp-json\/wp\/v2\/comments?post=2227"}],"version-history":[{"count":4,"href":"https:\/\/cero.com.pt\/en\/wp-json\/wp\/v2\/pages\/2227\/revisions"}],"predecessor-version":[{"id":2770,"href":"https:\/\/cero.com.pt\/en\/wp-json\/wp\/v2\/pages\/2227\/revisions\/2770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cero.com.pt\/en\/wp-json\/wp\/v2\/media\/1694"}],"wp:attachment":[{"href":"https:\/\/cero.com.pt\/en\/wp-json\/wp\/v2\/media?parent=2227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}